{"id":18331,"date":"2026-05-11T18:23:37","date_gmt":"2026-05-11T16:23:37","guid":{"rendered":"https:\/\/janfigel.com\/?p=18331"},"modified":"2026-05-12T18:30:03","modified_gmt":"2026-05-12T16:30:03","slug":"syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses","status":"publish","type":"post","link":"https:\/\/janfigel.com\/sk\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/","title":{"rendered":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2-1024x683.png\" alt=\"\" class=\"wp-image-18332\" srcset=\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2-1024x683.png 1024w, https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2-300x200.png 300w, https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2-768x512.png 768w, https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2-18x12.png 18w, https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">DPA\/SIPA \/ \u00a9 Moawia Atrash<\/figcaption><\/figure>\n\n\n\n<p>TRIBUNE. \u00c0 l\u2019heure o\u00f9 l\u2019Union europ\u00e9enne engage un dialogue de haut niveau avec la Syrie pour accompagner sa reconstruction \u00e9conomique, plusieurs associations de d\u00e9fense des libert\u00e9s religieuses alertent sur le sort des chr\u00e9tiens et des autres minorit\u00e9s du pays.<\/p>\n\n\n\n<p>Le \u00ab&nbsp;premier dialogue politique de haut niveau UE-Syrie&nbsp;\u00bb se tiendra le lundi&nbsp;11&nbsp;mai, \u00e0 l\u2019occasion de la r\u00e9union du Conseil des affaires \u00e9trang\u00e8res de l\u2019Union europ\u00e9enne. Les ministres des affaires \u00e9trang\u00e8res des \u00c9tats membres y discuteront&nbsp;<em>\u00ab&nbsp;des meilleurs moyens de soutenir la transition dans le pays&nbsp;\u00bb<\/em>. Apr\u00e8s la lev\u00e9e, en 2025, des sanctions \u00e9conomiques impos\u00e9es \u00e0 la&nbsp;<a href=\"https:\/\/www.lejdd.fr\/Tags\/Syrie\" target=\"_blank\" rel=\"noreferrer noopener\">Syrie<\/a>&nbsp;depuis 2011, l\u2019objectif est d\u00e9sormais d\u2019encourager la reprise \u00e9conomique du pays \u00e0 travers les investissements, les \u00e9changes commerciaux, ainsi que le retour des Syriens d\u00e9plac\u00e9s et des r\u00e9fugi\u00e9s.<\/p>\n\n\n\n<p>Alors que 90&nbsp;% des Syriens vivent aujourd\u2019hui sous le seuil de pauvret\u00e9, nous ne pouvons que saluer cette volont\u00e9 d\u2019aider la Syrie \u00e0 se reconstruire. Le redressement \u00e9conomique du pays est \u00e0 la fois n\u00e9cessaire et urgent. Cependant, nous ne pouvons ignorer les profondes inqui\u00e9tudes des chr\u00e9tiens, ainsi que d\u2019autres composantes de la soci\u00e9t\u00e9 syrienne, notamment les Alaouites, les Druzes, les Isma\u00e9liens et les Y\u00e9zidis. Les d\u00e9clarations des nouveaux dirigeants syriens se veulent rassurantes. La libert\u00e9 de culte demeure globalement tol\u00e9r\u00e9e. N\u00e9anmoins, au cours des dix-huit derniers mois, plusieurs d\u00e9cisions et comportements des nouvelles autorit\u00e9s ont continu\u00e9 d\u2019alimenter les craintes pour l\u2019avenir.<\/p>\n\n\n\n<p>Le lendemain de l\u2019attaque islamiste contre l\u2019\u00e9glise Saint-\u00c9lie de Damas, le 22&nbsp;juin 2025, qui a fait vingt-cinq morts et plus de soixante bless\u00e9s, le patriarche grec orthodoxe Jean X a \u00e9t\u00e9 la cible d\u2019une campagne de diffamation. \u00c0 la suite de cet attentat, le Parlement europ\u00e9en a rappel\u00e9, dans sa r\u00e9solution du 10&nbsp;juillet 2025, l\u2019urgence de prot\u00e9ger toutes les communaut\u00e9s religieuses en Syrie. Pourtant, ces communaut\u00e9s continuent de subir quotidiennement des attaques&nbsp;: enl\u00e8vements, assassinats, pillages, expropriations et extorsions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019effacement des chr\u00e9tiens<\/h2>\n\n\n\n<p>D\u00e9but mars&nbsp;2025, des milices affili\u00e9es au gouvernement ont d\u00e9lib\u00e9r\u00e9ment massacr\u00e9 des populations alaouites dans les r\u00e9gions c\u00f4ti\u00e8res de Lattaqui\u00e9 et Tartous, faisant plus de 1 400 morts. En juillet&nbsp;2025, des affrontements meurtriers entre groupes arm\u00e9s druzes, clans b\u00e9douins et forces gouvernementales ont caus\u00e9 plus de 1 700 morts dans la r\u00e9gion druze de Soue\u00efda. Depuis la chute du r\u00e9gime Assad, des dizaines de femmes alaouites ont \u00e9galement \u00e9t\u00e9 enlev\u00e9es ou port\u00e9es disparues dans un climat d\u2019impunit\u00e9. Le 1er&nbsp;mai 2026, un dignitaire religieux chiite a \u00e9t\u00e9 tu\u00e9 pr\u00e8s de Damas dans un attentat \u00e0 la bombe visant son v\u00e9hicule.<\/p>\n\n\n\n<p>Dans la nuit du 27&nbsp;mars 2026, des bandes islamistes ont attaqu\u00e9 les habitants de Sqaylabiyah, ville chr\u00e9tienne du centre de la Syrie, pillant des commerces et terrorisant la population sans aucune intervention des forces de s\u00e9curit\u00e9 gouvernementales. Cette attaque a conduit les chr\u00e9tiens syriens \u00e0 annuler les c\u00e9l\u00e9brations publiques et les processions traditionnellement organis\u00e9es pour le dimanche des Rameaux et P\u00e2ques, afin d\u2019alerter sur l\u2019incapacit\u00e9 du gouvernement \u00e0 assurer leur protection.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Pour beaucoup, l\u2019avenir prend d\u00e9sormais la forme de l\u2019\u00e9migration forc\u00e9e, de l\u2019exil et du d\u00e9racinement<\/p>\n<\/blockquote>\n\n\n\n<p>Au-del\u00e0 de cette violence visible, la vie quotidienne des chr\u00e9tiens syriens et de toutes les autres communaut\u00e9s, sauf les islamistes, est de plus en plus marqu\u00e9e par des pressions sociales&nbsp;: atteintes aux droits des femmes, harc\u00e8lement de rue visant les femmes qui ne portent pas le voile, et multiplication de marches de pr\u00e9dication islamiste appelant \u00e0 rejoindre la \u00ab&nbsp;vraie&nbsp;\u00bb religion, parfois avec le soutien du minist\u00e8re de l\u2019\u00c9ducation et de l\u2019appareil judiciaire. La d\u00e9cision d\u2019interdire l\u2019alcool dans toute la province de Damas, tout en en restreignant la vente \u00e0 certains quartiers chr\u00e9tiens comme dans des ghettos, a \u00e9t\u00e9 v\u00e9cue par de nombreux chr\u00e9tiens syriens comme une profonde humiliation les associant \u00e0 une pratique pr\u00e9sent\u00e9e comme immorale.<\/p>\n\n\n\n<p>En 2011, les chr\u00e9tiens repr\u00e9sentaient pr\u00e8s de 10&nbsp;% de la population syrienne. Aujourd\u2019hui, ils ne repr\u00e9sentent plus qu\u2019environ 3&nbsp;%. Pour beaucoup, l\u2019avenir prend d\u00e9sormais la forme de l\u2019\u00e9migration forc\u00e9e, de l\u2019exil et du d\u00e9racinement. C\u2019est pour eux, et pour l\u2019ensemble des diff\u00e9rentes communaut\u00e9s religieuses de Syrie, que notre coalition d\u2019associations appelle le Conseil de l\u2019Union europ\u00e9enne \u00e0 conditionner ce \u00ab&nbsp;premier dialogue politique de haut niveau UE-Syrie&nbsp;\u00bb \u00e0&nbsp;:<\/p>\n\n\n\n<p>&#8211; une v\u00e9ritable libert\u00e9 religieuse, afin que toutes les communaut\u00e9s religieuses puissent vivre publiquement leur foi sans peur ni restriction&nbsp;;<\/p>\n\n\n\n<p>&#8211; le respect de la soci\u00e9t\u00e9 civile et l\u2019inclusion r\u00e9elle de toutes les composantes du peuple syrien dans la reconstruction politique du pays.<\/p>\n\n\n\n<p>Les chr\u00e9tiens, alaouites, druzes, isma\u00e9liens et y\u00e9zidis de Syrie ne demandent rien d\u2019autre que d\u2019\u00eatre reconnus pour ce qu\u2019ils sont, des Syriens \u00e0 part enti\u00e8re&nbsp;: non comme des minorit\u00e9s tol\u00e9r\u00e9es ou des citoyens de seconde zone, mais comme des acteurs pleinement l\u00e9gitimes de la reconstruction institutionnelle, politique et sociale de leur pays. Ce qui se joue aujourd\u2019hui, c\u2019est leur droit \u00e0 continuer de vivre sur leur terre. \u00c0 cet \u00e9gard, une intervention lucide et vigilante de l\u2019<a href=\"https:\/\/www.lejdd.fr\/Tags\/Union-europeenne\" target=\"_blank\" rel=\"noreferrer noopener\">Union europ\u00e9enne<\/a>&nbsp;peut contribuer \u00e0 une reconstruction durable et v\u00e9ritablement pluraliste de la Syrie, afin qu\u2019elle ne devienne pas un \u00c9tat islamique homog\u00e8ne et radical gouvern\u00e9 exclusivement par la charia.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Les signataires<\/h3>\n\n\n\n<p>\u2022 Benjamin Blanchard, directeur g\u00e9n\u00e9ral de SOS Chr\u00e9tiens d\u2019Orient<\/p>\n\n\n\n<p>\u2022 Thibault van den Bossche, charg\u00e9 de plaidoyer au Centre europ\u00e9en pour le droit et la justice (ECLJ)<\/p>\n\n\n\n<p>\u2022 Rafic Abou Fadel, pr\u00e9sident du Conseil des chr\u00e9tiens d\u2019Orient<\/p>\n\n\n\n<p>\u2022 Joel Veldkamp, directeur du plaidoyer \u00e0 Christian Solidarity International (CSI)<\/p>\n\n\n\n<p>\u2022 Anastasia Hartman, charg\u00e9e de plaidoyer aupr\u00e8s de l\u2019Union europ\u00e9enne \u00e0 Open Doors International<\/p>\n\n\n\n<p>\u2022 Jens Kreinath, directeur de l\u2019Institute for the Documentation of Human Rights Violations against Religious Minorities in the Levant (IDHRV-ARMIL)<\/p>\n\n\n\n<p>\u2022 Thierry Valle, pr\u00e9sident de CAP Libert\u00e9 de Conscience<\/p>\n\n\n\n<p>\u2022 Jan Figel, president de FOREF Europe, ancien commissaire europ\u00e9en<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a href=\"https:\/\/www.lejdd.fr\/International\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses-173670\">https:\/\/www.lejdd.fr\/International\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses-173670<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>TRIBUNE. \u00c0 l\u2019heure o\u00f9 l\u2019Union europ\u00e9enne engage un dialogue de haut niveau avec la Syrie pour accompagner sa reconstruction \u00e9conomique, plusieurs associations de d\u00e9fense des libert\u00e9s religieuses alertent sur le sort des chr\u00e9tiens et des autres minorit\u00e9s du pays. Le \u00ab&nbsp;premier dialogue politique de haut niveau UE-Syrie&nbsp;\u00bb se tiendra le lundi&nbsp;11&nbsp;mai, \u00e0 l\u2019occasion de la [&hellip;]<\/p>","protected":false},"author":1,"featured_media":18332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[339],"tags":[],"class_list":["post-18331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/janfigel.com\/sk\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e\" \/>\n<meta property=\"og:description\" content=\"TRIBUNE. \u00c0 l\u2019heure o\u00f9 l\u2019Union europ\u00e9enne engage un dialogue de haut niveau avec la Syrie pour accompagner sa reconstruction \u00e9conomique, plusieurs associations de d\u00e9fense des libert\u00e9s religieuses alertent sur le sort des chr\u00e9tiens et des autres minorit\u00e9s du pays. Le \u00ab&nbsp;premier dialogue politique de haut niveau UE-Syrie&nbsp;\u00bb se tiendra le lundi&nbsp;11&nbsp;mai, \u00e0 l\u2019occasion de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/janfigel.com\/sk\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\" \/>\n<meta property=\"og:site_name\" content=\"J\u00e1n Fige\u013e\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Jn-Fige-prv-slovensk-eurokomisr-100064782245760\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T16:23:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adamjanfigel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@janfigel\" \/>\n<meta name=\"twitter:site\" content=\"@janfigel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adamjanfigel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\"},\"author\":{\"name\":\"adamjanfigel\",\"@id\":\"https:\/\/janfigel.com\/sk\/#\/schema\/person\/41a139a900161f4b4cab75b4d7c55fc1\"},\"headline\":\"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses\",\"datePublished\":\"2026-05-11T16:23:37+00:00\",\"dateModified\":\"2026-05-12T16:30:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\"},\"wordCount\":1096,\"publisher\":{\"@id\":\"https:\/\/janfigel.com\/sk\/#organization\"},\"image\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png\",\"articleSection\":[\"Fran\u00e7ais\"],\"inLanguage\":\"sk\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\",\"url\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\",\"name\":\"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e\",\"isPartOf\":{\"@id\":\"https:\/\/janfigel.com\/sk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png\",\"datePublished\":\"2026-05-11T16:23:37+00:00\",\"dateModified\":\"2026-05-12T16:30:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#breadcrumb\"},\"inLanguage\":\"sk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sk\",\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage\",\"url\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png\",\"contentUrl\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/janfigel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/janfigel.com\/sk\/#website\",\"url\":\"https:\/\/janfigel.com\/sk\/\",\"name\":\"J\u00e1n Fige\u013e\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/janfigel.com\/sk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/janfigel.com\/sk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/janfigel.com\/sk\/#organization\",\"name\":\"J\u00e1n Fige\u013e\",\"url\":\"https:\/\/janfigel.com\/sk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk\",\"@id\":\"https:\/\/janfigel.com\/sk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2025\/06\/JF_Navy-Blue-1.png\",\"contentUrl\":\"https:\/\/janfigel.com\/wp-content\/uploads\/2025\/06\/JF_Navy-Blue-1.png\",\"width\":2451,\"height\":2451,\"caption\":\"J\u00e1n Fige\u013e\"},\"image\":{\"@id\":\"https:\/\/janfigel.com\/sk\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Jn-Fige-prv-slovensk-eurokomisr-100064782245760\/\",\"https:\/\/x.com\/janfigel\",\"https:\/\/sk.linkedin.com\/in\/jn-fige-110354126\",\"https:\/\/www.instagram.com\/figeljan\/\",\"https:\/\/www.youtube.com\/@janfigel_eu\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/janfigel.com\/sk\/#\/schema\/person\/41a139a900161f4b4cab75b4d7c55fc1\",\"name\":\"adamjanfigel\",\"sameAs\":[\"http:\/\/janfigel.com\"],\"url\":\"https:\/\/janfigel.com\/sk\/author\/admin_ajf\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/janfigel.com\/sk\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/","og_locale":"sk_SK","og_type":"article","og_title":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e","og_description":"TRIBUNE. \u00c0 l\u2019heure o\u00f9 l\u2019Union europ\u00e9enne engage un dialogue de haut niveau avec la Syrie pour accompagner sa reconstruction \u00e9conomique, plusieurs associations de d\u00e9fense des libert\u00e9s religieuses alertent sur le sort des chr\u00e9tiens et des autres minorit\u00e9s du pays. Le \u00ab&nbsp;premier dialogue politique de haut niveau UE-Syrie&nbsp;\u00bb se tiendra le lundi&nbsp;11&nbsp;mai, \u00e0 l\u2019occasion de la [&hellip;]","og_url":"https:\/\/janfigel.com\/sk\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/","og_site_name":"J\u00e1n Fige\u013e","article_publisher":"https:\/\/www.facebook.com\/p\/Jn-Fige-prv-slovensk-eurokomisr-100064782245760\/","article_published_time":"2026-05-11T16:23:37+00:00","article_modified_time":"2026-05-12T16:30:03+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png","type":"image\/png"}],"author":"adamjanfigel","twitter_card":"summary_large_image","twitter_creator":"@janfigel","twitter_site":"@janfigel","twitter_misc":{"Written by":"adamjanfigel","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#article","isPartOf":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/"},"author":{"name":"adamjanfigel","@id":"https:\/\/janfigel.com\/sk\/#\/schema\/person\/41a139a900161f4b4cab75b4d7c55fc1"},"headline":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses","datePublished":"2026-05-11T16:23:37+00:00","dateModified":"2026-05-12T16:30:03+00:00","mainEntityOfPage":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/"},"wordCount":1096,"publisher":{"@id":"https:\/\/janfigel.com\/sk\/#organization"},"image":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage"},"thumbnailUrl":"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png","articleSection":["Fran\u00e7ais"],"inLanguage":"sk"},{"@type":"WebPage","@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/","url":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/","name":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses - J\u00e1n Fige\u013e","isPartOf":{"@id":"https:\/\/janfigel.com\/sk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage"},"image":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage"},"thumbnailUrl":"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png","datePublished":"2026-05-11T16:23:37+00:00","dateModified":"2026-05-12T16:30:03+00:00","breadcrumb":{"@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#breadcrumb"},"inLanguage":"sk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/"]}]},{"@type":"ImageObject","inLanguage":"sk","@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#primaryimage","url":"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png","contentUrl":"https:\/\/janfigel.com\/wp-content\/uploads\/2026\/05\/image-2.png","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/janfigel.com\/2026\/05\/11\/syrie-leurope-doit-exiger-la-protection-de-toutes-les-communautes-religieuses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/janfigel.com\/"},{"@type":"ListItem","position":2,"name":"Syrie : l\u2019Europe doit exiger la protection de toutes les communaut\u00e9s religieuses"}]},{"@type":"WebSite","@id":"https:\/\/janfigel.com\/sk\/#website","url":"https:\/\/janfigel.com\/sk\/","name":"J\u00e1n Fige\u013e","description":"","publisher":{"@id":"https:\/\/janfigel.com\/sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/janfigel.com\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk"},{"@type":"Organization","@id":"https:\/\/janfigel.com\/sk\/#organization","name":"J\u00e1n Fige\u013e","url":"https:\/\/janfigel.com\/sk\/","logo":{"@type":"ImageObject","inLanguage":"sk","@id":"https:\/\/janfigel.com\/sk\/#\/schema\/logo\/image\/","url":"https:\/\/janfigel.com\/wp-content\/uploads\/2025\/06\/JF_Navy-Blue-1.png","contentUrl":"https:\/\/janfigel.com\/wp-content\/uploads\/2025\/06\/JF_Navy-Blue-1.png","width":2451,"height":2451,"caption":"J\u00e1n Fige\u013e"},"image":{"@id":"https:\/\/janfigel.com\/sk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Jn-Fige-prv-slovensk-eurokomisr-100064782245760\/","https:\/\/x.com\/janfigel","https:\/\/sk.linkedin.com\/in\/jn-fige-110354126","https:\/\/www.instagram.com\/figeljan\/","https:\/\/www.youtube.com\/@janfigel_eu"]},{"@type":"Person","@id":"https:\/\/janfigel.com\/sk\/#\/schema\/person\/41a139a900161f4b4cab75b4d7c55fc1","name":"adamjanfigel","sameAs":["http:\/\/janfigel.com"],"url":"https:\/\/janfigel.com\/sk\/author\/admin_ajf\/"}]}},"_links":{"self":[{"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/posts\/18331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/comments?post=18331"}],"version-history":[{"count":1,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/posts\/18331\/revisions"}],"predecessor-version":[{"id":18333,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/posts\/18331\/revisions\/18333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/media\/18332"}],"wp:attachment":[{"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/media?parent=18331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/categories?post=18331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/janfigel.com\/sk\/wp-json\/wp\/v2\/tags?post=18331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}